{"id":184553,"date":"2024-08-06T10:22:38","date_gmt":"2024-08-06T01:22:38","guid":{"rendered":"https:\/\/www.isseido-books.co.jp\/shop\/?p=184553"},"modified":"2024-08-06T10:24:40","modified_gmt":"2024-08-06T01:24:40","slug":"%e4%b8%ad%e5%9b%bd%e4%b8%ad%e4%b8%96%e4%bb%8f%e6%95%99%e5%8f%b2%e8%ab%96%e6%94%b7%e3%80%80%e5%a1%9a%e6%9c%ac%e5%96%84%e9%9a%86%e8%91%97%e4%bd%9c%e9%9b%86%e7%ac%ac%e4%b8%89%e5%b7%bb","status":"publish","type":"post","link":"https:\/\/www.isseido-books.co.jp\/shop\/item\/itemwasho\/184553\/%e4%b8%ad%e5%9b%bd%e4%b8%ad%e4%b8%96%e4%bb%8f%e6%95%99%e5%8f%b2%e8%ab%96%e6%94%b7%e3%80%80%e5%a1%9a%e6%9c%ac%e5%96%84%e9%9a%86%e8%91%97%e4%bd%9c%e9%9b%86%e7%ac%ac%e4%b8%89%e5%b7%bb\/","title":{"rendered":"\u4e2d\u56fd\u4e2d\u4e16\u4ecf\u6559\u53f2\u8ad6\u6537"},"content":{"rendered":"<div class=\"loopimg\"><a href=\"https:\/\/www.isseido-books.co.jp\/shop\/item\/itemwasho\/184553\/%e4%b8%ad%e5%9b%bd%e4%b8%ad%e4%b8%96%e4%bb%8f%e6%95%99%e5%8f%b2%e8%ab%96%e6%94%b7%e3%80%80%e5%a1%9a%e6%9c%ac%e5%96%84%e9%9a%86%e8%91%97%e4%bd%9c%e9%9b%86%e7%ac%ac%e4%b8%89%e5%b7%bb\/\"><\/a><\/div><div class=\"loopexp\"><div class=\"field\"><p>\u585a\u672c\u5584\u9686\u8457\u4f5c\u96c6\uff08\u4e09\uff09<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"loopimg\"><a href=\"https:\/\/www.isseido-books.co.jp\/shop\/item\/itemwasho\/184553\/%e4%b8%ad%e5%9b%bd%e4%b8%ad%e4%b8%96%e4%bb%8f%e6%95%99%e5%8f%b2%e8%ab%96%e6%94%b7%e3%80%80%e5%a1%9a%e6%9c%ac%e5%96%84%e9%9a%86%e8%91%97%e4%bd%9c%e9%9b%86%e7%ac%ac%e4%b8%89%e5%b7%bb\/\"><\/a><\/div><div class=\"loopexp\"><div class=\"field\"><p>\u585a\u672c\u5584\u9686\u8457\u4f5c\u96c6\uff08\u4e09\uff09<\/p>\n<\/div><\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,12,44],"tags":[],"class_list":{"0":"post-184553","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-itemwasho","7":"category-item","8":"category-shukyo"},"_links":{"self":[{"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/posts\/184553"}],"collection":[{"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/comments?post=184553"}],"version-history":[{"count":4,"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/posts\/184553\/revisions"}],"predecessor-version":[{"id":184555,"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/posts\/184553\/revisions\/184555"}],"wp:attachment":[{"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/media?parent=184553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/categories?post=184553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.isseido-books.co.jp\/shop\/wp-json\/wp\/v2\/tags?post=184553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}